{"id":9,"date":"2019-08-26T00:29:09","date_gmt":"2019-08-26T00:29:09","guid":{"rendered":"http:\/\/ardoglobalventures.com\/?page_id=9"},"modified":"2019-11-07T00:09:20","modified_gmt":"2019-11-07T00:09:20","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/ardoglobalventures.com\/our-work\/contact-us\/","title":{"rendered":"Contact Us"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>&lt;iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m26!1m12!1m3!1d4040743.408404709!2d7.136901245664567!3d8.495639131474539!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!4m11!3e6!4m3!3m2!1d9.058713599999999!2d7.448985599999999!4m5!1s0x10f929afffffffb9%3A0xe9fc0b72589a756e!2staraba%20state%20university!3m2!1d8.9002768!2d11.3168132!5e0!3m2!1sen!2sng!4v1573084907030!5m2!1sen!2sng\" width=\"600\" height=\"450\" frameborder=\"0\" style=\"border:0;\" allowfullscreen=\"\">&lt;\/iframe><\/code><\/pre>\n\n\n<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-71\"><form id=\"wpforms-form-71\" class=\"wpforms-validate wpforms-form\" data-formid=\"71\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/our-work\/wp-json\/wp\/v2\/pages\/9\" data-token=\"7037d50c7a568a4a5e1fce113be4fba2\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-71-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-71-field_0\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-71-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" required><label for=\"wpforms-71-field_0\" class=\"wpforms-field-sublabel after \">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-71-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" required><label for=\"wpforms-71-field_0-last\" class=\"wpforms-field-sublabel after \">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-71-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-71-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-71-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-71-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-71-field_2\">Comment or Message <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-71-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-71-field-hp\" class=\"wpforms-field-label\">Name<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-71-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"71\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-71\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ardoglobalventures.com\/our-work\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ardoglobalventures.com\/our-work\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ardoglobalventures.com\/our-work\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ardoglobalventures.com\/our-work\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ardoglobalventures.com\/our-work\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":4,"href":"https:\/\/ardoglobalventures.com\/our-work\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"predecessor-version":[{"id":84,"href":"https:\/\/ardoglobalventures.com\/our-work\/wp-json\/wp\/v2\/pages\/9\/revisions\/84"}],"wp:attachment":[{"href":"https:\/\/ardoglobalventures.com\/our-work\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}